{"id":60971,"date":"2021-04-22T12:52:00","date_gmt":"2021-04-22T12:52:00","guid":{"rendered":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/"},"modified":"2024-08-26T11:00:56","modified_gmt":"2024-08-26T14:00:56","slug":"conheca-a-pronuncia-do-l-no-espanhol","status":"publish","type":"post","link":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/","title":{"rendered":"Conhe\u00e7a a pron\u00fancia do L no espanhol"},"content":{"rendered":"<h2>A pron\u00fancia do L<\/h2>\n<p><em>\u00a1Hola, hermosuras! \u00bfC\u00f3mo est\u00e1n?<\/em><br \/>\nSe voc\u00ea \u00e9 brasileiro(a) e est\u00e1 aprendendo espanhol, uma das primeiras coisas que voc\u00ea precisa saber \u00e9 que, diferente do que acontece em portugu\u00eas, o L do espanhol vai ter sempre o mesmo som! N\u00e3o entendeu?   Vamos ver alguns exemplos!<br \/>\nPense comigo: em portugu\u00eas, como dizemos as palavras \u201cfinal\u201d e \u201calguma\u201d? Reparou que o L acaba ficando com som de U?   Em espanhol, isso n\u00e3o acontece! O L vai ser sempre pronunciado do mesmo jeito, seja no come\u00e7o, no meio ou no fim das palavras!<\/p>\n<p>E para fazer esse som, voc\u00ea s\u00f3 precisa colocar a ponta da l\u00edngua atr\u00e1s dos seus dentes da frente, na parte de cima da boca, do mesmo jeito que fazemos quando dizemos \u201cl\u00e1pis\u201d ou \u201catleta\u201d. Bem tranquilo, n\u00e9?<\/p>\n<p>Agora, para voc\u00ea praticar o L em espanhol, que tal um desafio? Tente dizer este trava-l\u00ednguas aqui, lembrando sempre da ponta da l\u00edngua atr\u00e1s dos dentes!<br \/>\nLa piel del jovial Manuel, siempre fiel a la ley local, luce como la miel de un panal singular.<br \/>\nA pele do jovial Manuel, sempre fiel \u00e0 lei local, destaca-se como o mel de uma colmeia singular.<\/p>\n<p>A gente sabe que n\u00e3o faz sentido, \u00e9 s\u00f3 pra voc\u00ea treinar mesmo!<\/p>\n<p>E a\u00ed, conseguiu? N\u00e3o se esque\u00e7a de compartilhar este v\u00eddeo com os seus amigos que tamb\u00e9m est\u00e3o aprendendo espanhol, para voc\u00eas praticarem juntos essa pron\u00fancia! Nos vemos na pr\u00f3xima dica, \u00a1chao!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabia que o som do L em portugu\u00eas e em espanhol n\u00e3o \u00e9 o mesmo? \u00c9 o que eu vou te ensinar na dica de hoje!<\/p>\n","protected":false},"author":6,"featured_media":60972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":[184],"meta":{"inline_featured_image":false,"footnotes":""},"categories":[169],"tags":[],"trilha":[],"class_list":["post-60971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pronuncia","format-videos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conhe\u00e7a a pron\u00fancia do L no espanhol<\/title>\n<meta name=\"description\" content=\"Voc\u00ea sabia que o som do L em portugu\u00eas e em espanhol n\u00e3o \u00e9 o mesmo? \u00c9 o que eu vou te ensinar na dica de hoje!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a a pron\u00fancia do L no espanhol\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea sabia que o som do L em portugu\u00eas e em espanhol n\u00e3o \u00e9 o mesmo? \u00c9 o que eu vou te ensinar na dica de hoje!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/\" \/>\n<meta property=\"og:site_name\" content=\"Fluency.io Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-22T12:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-26T14:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a4fa1771a1a63e5b0de67_Background-52.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"461\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marcelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/\"},\"author\":{\"name\":\"marcelo\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"headline\":\"Conhe\u00e7a a pron\u00fancia do L no espanhol\",\"datePublished\":\"2021-04-22T12:52:00+00:00\",\"dateModified\":\"2024-08-26T14:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/\"},\"wordCount\":267,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/606a4fa1771a1a63e5b0de67_Background-52.jpg\",\"articleSection\":[\"Pron\u00fancia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/\",\"name\":\"Conhe\u00e7a a pron\u00fancia do L no espanhol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/606a4fa1771a1a63e5b0de67_Background-52.jpg\",\"datePublished\":\"2021-04-22T12:52:00+00:00\",\"dateModified\":\"2024-08-26T14:00:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"description\":\"Voc\u00ea sabia que o som do L em portugu\u00eas e em espanhol n\u00e3o \u00e9 o mesmo? \u00c9 o que eu vou te ensinar na dica de hoje!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/606a4fa1771a1a63e5b0de67_Background-52.jpg\",\"contentUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/606a4fa1771a1a63e5b0de67_Background-52.jpg\",\"width\":820,\"height\":461,\"caption\":\"Conhe\u00e7a a pron\u00fancia do L no espanhol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/conheca-a-pronuncia-do-l-no-espanhol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluency.io\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conhe\u00e7a a pron\u00fancia do L no espanhol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/\",\"name\":\"Fluency Academy\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluency.io\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\",\"name\":\"marcelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"caption\":\"marcelo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a a pron\u00fancia do L no espanhol","description":"Voc\u00ea sabia que o som do L em portugu\u00eas e em espanhol n\u00e3o \u00e9 o mesmo? \u00c9 o que eu vou te ensinar na dica de hoje!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/","og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a a pron\u00fancia do L no espanhol","og_description":"Voc\u00ea sabia que o som do L em portugu\u00eas e em espanhol n\u00e3o \u00e9 o mesmo? \u00c9 o que eu vou te ensinar na dica de hoje!","og_url":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/","og_site_name":"Fluency.io Brasil","article_published_time":"2021-04-22T12:52:00+00:00","article_modified_time":"2024-08-26T14:00:56+00:00","og_image":[{"width":820,"height":461,"url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a4fa1771a1a63e5b0de67_Background-52.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marcelo","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/#article","isPartOf":{"@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/"},"author":{"name":"marcelo","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"headline":"Conhe\u00e7a a pron\u00fancia do L no espanhol","datePublished":"2021-04-22T12:52:00+00:00","dateModified":"2024-08-26T14:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/"},"wordCount":267,"commentCount":0,"image":{"@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a4fa1771a1a63e5b0de67_Background-52.jpg","articleSection":["Pron\u00fancia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/","url":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/","name":"Conhe\u00e7a a pron\u00fancia do L no espanhol","isPartOf":{"@id":"https:\/\/fluency.io\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/#primaryimage"},"image":{"@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a4fa1771a1a63e5b0de67_Background-52.jpg","datePublished":"2021-04-22T12:52:00+00:00","dateModified":"2024-08-26T14:00:56+00:00","author":{"@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"description":"Voc\u00ea sabia que o som do L em portugu\u00eas e em espanhol n\u00e3o \u00e9 o mesmo? \u00c9 o que eu vou te ensinar na dica de hoje!","breadcrumb":{"@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/#primaryimage","url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a4fa1771a1a63e5b0de67_Background-52.jpg","contentUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a4fa1771a1a63e5b0de67_Background-52.jpg","width":820,"height":461,"caption":"Conhe\u00e7a a pron\u00fancia do L no espanhol"},{"@type":"BreadcrumbList","@id":"https:\/\/fluency.io\/br\/blog\/conheca-a-pronuncia-do-l-no-espanhol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluency.io\/br\/"},{"@type":"ListItem","position":2,"name":"Conhe\u00e7a a pron\u00fancia do L no espanhol"}]},{"@type":"WebSite","@id":"https:\/\/fluency.io\/br\/#website","url":"https:\/\/fluency.io\/br\/","name":"Fluency Academy","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluency.io\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f","name":"marcelo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","caption":"marcelo"}}]}},"_links":{"self":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/60971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/comments?post=60971"}],"version-history":[{"count":1,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/60971\/revisions"}],"predecessor-version":[{"id":67087,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/60971\/revisions\/67087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media\/60972"}],"wp:attachment":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media?parent=60971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/categories?post=60971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/tags?post=60971"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/format?post=60971"},{"taxonomy":"trilha","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/trilha?post=60971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}