{"id":63253,"date":"2021-05-02T12:48:00","date_gmt":"2021-05-02T12:48:00","guid":{"rendered":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/"},"modified":"2024-12-11T09:15:29","modified_gmt":"2024-12-11T12:15:29","slug":"aula-de-frances-02-se-apresentando-em-frances","status":"publish","type":"post","link":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/","title":{"rendered":"Aula de franc\u00eas: Eu sou brasileira!"},"content":{"rendered":"<h2>Nacionalidades!<\/h2>\n<p><em>Salut !<\/em> Seja muito bem-vindo, muito bem-vinda, a mais uma aula de franc\u00eas do projeto de aulas GRATUITAS da <strong>Fluency Academy<\/strong>! Toda semana voc\u00ea vai assistir uma aula completa de franc\u00eas com material gratuito para baixar e complementar seus estudos. Essa aula aconteceu em 18 de agosto de 2020.<\/p>\n<p>A aula de hoje \u00e9 referente ao epis\u00f3dio Walk &#8216;n&#8217; Talk Essentials Franc\u00eas #02.<\/p>\n<p>Quer dar um passo al\u00e9m no seu aprendizado? Inscreva-se agora no <strong><a href=\"https:\/\/fluency.io\/br\/cursos\/frances\/\" target=\"_new\" rel=\"noopener\">curso de franc\u00eas<\/a><\/strong> da Fluency Academy e alcance a flu\u00eancia com o melhor m\u00e9todo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vamos para mais uma aula completa de franc\u00eas? Nessa aula a prof Ana vai te dar \u00f3timas dicas sobre como falar da sua nacionalidade!<\/p>\n","protected":false},"author":6,"featured_media":63254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":[184],"meta":{"inline_featured_image":false,"footnotes":""},"categories":[160],"tags":[],"trilha":[213],"class_list":["post-63253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gramatica","format-videos","trilha-aulas-de-frances"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aula de franc\u00eas: Eu sou brasileira!<\/title>\n<meta name=\"description\" content=\"Vamos para mais uma aula completa de franc\u00eas? Nessa aula a prof Ana vai te dar \u00f3timas dicas sobre como falar da sua nacionalidade!\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aula de franc\u00eas: Eu sou brasileira!\" \/>\n<meta property=\"og:description\" content=\"Vamos para mais uma aula completa de franc\u00eas? Nessa aula a prof Ana vai te dar \u00f3timas dicas sobre como falar da sua nacionalidade!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/\" \/>\n<meta property=\"og:site_name\" content=\"Fluency.io Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-02T12:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-11T12:15:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a43b84f1ab8fd0f6a6713_Background-33.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"461\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marcelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/\"},\"author\":{\"name\":\"marcelo\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"headline\":\"Aula de franc\u00eas: Eu sou brasileira!\",\"datePublished\":\"2021-05-02T12:48:00+00:00\",\"dateModified\":\"2024-12-11T12:15:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/\"},\"wordCount\":99,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/606a43b84f1ab8fd0f6a6713_Background-33.jpg\",\"articleSection\":[\"Gram\u00e1tica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/\",\"name\":\"Aula de franc\u00eas: Eu sou brasileira!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/606a43b84f1ab8fd0f6a6713_Background-33.jpg\",\"datePublished\":\"2021-05-02T12:48:00+00:00\",\"dateModified\":\"2024-12-11T12:15:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"description\":\"Vamos para mais uma aula completa de franc\u00eas? Nessa aula a prof Ana vai te dar \u00f3timas dicas sobre como falar da sua nacionalidade!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/606a43b84f1ab8fd0f6a6713_Background-33.jpg\",\"contentUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/606a43b84f1ab8fd0f6a6713_Background-33.jpg\",\"width\":820,\"height\":461,\"caption\":\"Aula de franc\u00eas #02: Eu sou brasileira!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/aula-de-frances-02-se-apresentando-em-frances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluency.io\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aula de franc\u00eas: Eu sou brasileira!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/\",\"name\":\"Fluency Academy\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluency.io\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\",\"name\":\"marcelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"caption\":\"marcelo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aula de franc\u00eas: Eu sou brasileira!","description":"Vamos para mais uma aula completa de franc\u00eas? Nessa aula a prof Ana vai te dar \u00f3timas dicas sobre como falar da sua nacionalidade!","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"pt_BR","og_type":"article","og_title":"Aula de franc\u00eas: Eu sou brasileira!","og_description":"Vamos para mais uma aula completa de franc\u00eas? Nessa aula a prof Ana vai te dar \u00f3timas dicas sobre como falar da sua nacionalidade!","og_url":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/","og_site_name":"Fluency.io Brasil","article_published_time":"2021-05-02T12:48:00+00:00","article_modified_time":"2024-12-11T12:15:29+00:00","og_image":[{"width":820,"height":461,"url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a43b84f1ab8fd0f6a6713_Background-33.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marcelo","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/#article","isPartOf":{"@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/"},"author":{"name":"marcelo","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"headline":"Aula de franc\u00eas: Eu sou brasileira!","datePublished":"2021-05-02T12:48:00+00:00","dateModified":"2024-12-11T12:15:29+00:00","mainEntityOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/"},"wordCount":99,"commentCount":0,"image":{"@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a43b84f1ab8fd0f6a6713_Background-33.jpg","articleSection":["Gram\u00e1tica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/","url":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/","name":"Aula de franc\u00eas: Eu sou brasileira!","isPartOf":{"@id":"https:\/\/fluency.io\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/#primaryimage"},"image":{"@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a43b84f1ab8fd0f6a6713_Background-33.jpg","datePublished":"2021-05-02T12:48:00+00:00","dateModified":"2024-12-11T12:15:29+00:00","author":{"@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"description":"Vamos para mais uma aula completa de franc\u00eas? Nessa aula a prof Ana vai te dar \u00f3timas dicas sobre como falar da sua nacionalidade!","breadcrumb":{"@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/#primaryimage","url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a43b84f1ab8fd0f6a6713_Background-33.jpg","contentUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/606a43b84f1ab8fd0f6a6713_Background-33.jpg","width":820,"height":461,"caption":"Aula de franc\u00eas #02: Eu sou brasileira!"},{"@type":"BreadcrumbList","@id":"https:\/\/fluency.io\/br\/blog\/aula-de-frances-02-se-apresentando-em-frances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluency.io\/br\/"},{"@type":"ListItem","position":2,"name":"Aula de franc\u00eas: Eu sou brasileira!"}]},{"@type":"WebSite","@id":"https:\/\/fluency.io\/br\/#website","url":"https:\/\/fluency.io\/br\/","name":"Fluency Academy","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluency.io\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f","name":"marcelo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","caption":"marcelo"}}]}},"_links":{"self":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/63253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/comments?post=63253"}],"version-history":[{"count":3,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/63253\/revisions"}],"predecessor-version":[{"id":92114,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/63253\/revisions\/92114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media\/63254"}],"wp:attachment":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media?parent=63253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/categories?post=63253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/tags?post=63253"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/format?post=63253"},{"taxonomy":"trilha","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/trilha?post=63253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}