{"id":63908,"date":"2022-04-15T17:29:00","date_gmt":"2022-04-15T17:29:00","guid":{"rendered":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/"},"modified":"2025-02-14T18:29:18","modified_gmt":"2025-02-14T21:29:18","slug":"culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha","status":"publish","type":"post","link":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/","title":{"rendered":"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?"},"content":{"rendered":"<p><em>Hallihallo!<\/em>\u200d<\/p>\n<p>Neste epis\u00f3dio do Culture Talks, vamos falar um pouco mais sobre a comida t\u00edpica alem\u00e3! Qual comida aparece na sua cabe\u00e7a quando voc\u00ea pensa em algo t\u00edpico da Alemanha? Salsicha? Sim, mas tem muito mais! Vamos viajar para o norte, leste e oeste da Alemanha e descobrir a comida que os estados nos oferecem. Pronto, pronta? \ud83d\ude42<\/p>\n<h2 data-pm-slice=\"1 1 []\">1. Vocabul\u00e1rio B\u00e1sico<\/h2>\n<p>Vamos aprender algumas palavras e express\u00f5es que aparecem no podcast:<\/p>\n<ul data-spread=\"false\">\n<li><strong>Essen<\/strong> \u2013 comida<\/li>\n<li><strong>Gericht<\/strong> \u2013 prato<\/li>\n<li><strong>Wurst<\/strong> \u2013 salsicha<\/li>\n<li><strong>Kartoffel<\/strong> \u2013 batata<\/li>\n<li><strong>Sauerkraut<\/strong> \u2013 chucrute<\/li>\n<li><strong>Fisch<\/strong> \u2013 peixe<\/li>\n<li><strong>S\u00fc\u00dfigkeit<\/strong> \u2013 doce<\/li>\n<li><strong>Brot<\/strong> \u2013 p\u00e3o<\/li>\n<li><strong>Bier<\/strong> \u2013 cerveja<\/li>\n<li><strong>Spezialit\u00e4t<\/strong> \u2013 especialidade<\/li>\n<\/ul>\n<p><strong>Frases \u00fateis:<\/strong><\/p>\n<ul data-spread=\"false\">\n<li><em>Was isst du gerne?<\/em> (O que voc\u00ea gosta de comer?)<\/li>\n<li><em>Ich esse gerne&#8230;<\/em> (Eu gosto de comer&#8230;)<\/li>\n<li><em>Das ist lecker!<\/em> (Isso \u00e9 delicioso!)<\/li>\n<\/ul>\n<h2>2. Compreens\u00e3o do Podcast<\/h2>\n<p><strong>Perguntas de compreens\u00e3o:<\/strong> (Responda em portugu\u00eas ou alem\u00e3o)<\/p>\n<ol start=\"1\" data-spread=\"false\">\n<li>Qual \u00e9 a primeira comida que muitas pessoas pensam quando falam sobre a Alemanha?<\/li>\n<li>O podcast menciona que h\u00e1 mais op\u00e7\u00f5es de comida al\u00e9m da salsicha. Voc\u00ea pode citar duas outras comidas t\u00edpicas?<\/li>\n<li>Quais regi\u00f5es da Alemanha s\u00e3o exploradas no podcast?<\/li>\n<\/ol>\n<h2>3. Exerc\u00edcio de Vocabul\u00e1rio<\/h2>\n<p>Preencha as lacunas com as palavras do vocabul\u00e1rio aprendido:<\/p>\n<ol start=\"1\" data-spread=\"false\">\n<li>A _________ (salsicha) \u00e9 um prato muito comum na Alemanha.<\/li>\n<li>Muitos alem\u00e3es gostam de comer _________ (batata) como acompanhamento.<\/li>\n<li>O _________ (p\u00e3o) alem\u00e3o \u00e9 famoso por sua variedade e sabor.<\/li>\n<li>Uma bebida muito popular na Alemanha \u00e9 o _________ (cerveja).<\/li>\n<li>O _________ (chucrute) \u00e9 feito de repolho fermentado e \u00e9 um acompanhamento t\u00edpico.<\/li>\n<\/ol>\n<h2>4. Pr\u00e1tica de Escrita<\/h2>\n<p>Escreva um pequeno texto (3 a 5 frases) sobre sua comida favorita em alem\u00e3o. Use as palavras do vocabul\u00e1rio. Exemplo: <em>Ich esse gerne Bratwurst mit Sauerkraut. Das ist sehr lecker!<\/em><\/p>\n<h2>Respostas:<\/h2>\n<p><strong>Compreens\u00e3o do Podcast:<\/strong><\/p>\n<ol start=\"1\" data-spread=\"false\">\n<li>Salsicha (Wurst)<\/li>\n<li>Poss\u00edveis respostas: Kartoffeln (batata), Sauerkraut (chucrute), Brot (p\u00e3o), Fisch (peixe), etc.<\/li>\n<li>Norte, leste e oeste da Alemanha.<\/li>\n<\/ol>\n<p><strong>Exerc\u00edcio de Vocabul\u00e1rio:<\/strong><\/p>\n<ol start=\"1\" data-spread=\"false\">\n<li>Wurst<\/li>\n<li>Kartoffel<\/li>\n<li>Brot<\/li>\n<li>Bier<\/li>\n<li>Sauerkraut\u200d<\/li>\n<\/ol>\n<h3>\u200d<strong>Expans\u00e3o de vocabul\u00e1rio<\/strong>\u200d<\/h3>\n<p>\u200d<em>Pratos t\u00edpicos<\/em><br \/>\n\u200d<strong><em>der Labskaus<\/em><\/strong>\u200d<\/p>\n<p>\u200d<strong><em>das Matjesfilet<\/em><\/strong><br \/>\nO fil\u00e9 de arenque maturado em sal<\/p>\n<p>\u200d<strong><em>die Currywurst<\/em><\/strong><br \/>\nA salsicha de curry<strong><em>\u200d<\/em><\/strong><\/p>\n<p><strong><em>die K\u00f6nigsberger Klopse (pl.)<\/em><\/strong><br \/>\nAs bolinhas de carne de K\u00f6nigsberg<strong><em>\u200d<\/em><\/strong><\/p>\n<p><strong><em>das Leipziger Allerlei<\/em><\/strong><br \/>\nOs legumes regionais de Leipzig<strong><em>\u200d<\/em><\/strong><\/p>\n<p><strong><em>die Bratwurst<\/em><\/strong><br \/>\nA salsicha frita<strong><em>\u200d<\/em><\/strong><\/p>\n<p><strong><em>die Th\u00fcringer Kl\u00f6\u00dfe (pl.)<\/em><\/strong><br \/>\nOs bolinhos de massa da Tur\u00edngia<strong><em>\u200d<\/em><\/strong><\/p>\n<p><strong><em>die Frankfurter W\u00fcrstchen (pl.)<\/em><\/strong><br \/>\nAs salsichas de Frankfurt<strong><em>\u200d<\/em><\/strong><\/p>\n<p><strong><em>der Flammkuchen<\/em><\/strong><br \/>\nA torta <em>flamb\u00e9e<\/em><strong><em>\u200d<\/em><\/strong><\/p>\n<p><strong><em>die K\u00e4sesp\u00e4tzle (pl.)<\/em><\/strong><br \/>\nAs <em>Sp\u00e4tzle<\/em> de queijo<strong><em>\u200d<\/em><\/strong><\/p>\n<p><strong><em>das Wei\u00dfwurstfr\u00fchst\u00fcck<\/em><\/strong><br \/>\nO caf\u00e9 da manh\u00e3 com salsicha branca<\/p>\n<p>Agora pratique e divirta-se aprendendo alem\u00e3o!<\/p>\n<p><span style=\"font-weight: 400\">Curtiu o conte\u00fado? Confira o <\/span><a href=\"https:\/\/fluency.io\/br\/cursos\/alemao\/\"><span style=\"font-weight: 400\">curso de alem\u00e3o<\/span><\/a><span style=\"font-weight: 400\"> completo e veja os benef\u00edcios exclusivos para alunos aqui do portal.<\/span><\/p>\n<p>At\u00e9 o pr\u00f3ximo epis\u00f3dio, <em>tsch\u00fcss!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vamos fazer uma viagem culin\u00e1ria pela Alemanha?<\/p>\n","protected":false},"author":6,"featured_media":63909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":[183],"meta":{"inline_featured_image":false,"footnotes":""},"categories":[163],"tags":[],"trilha":[],"class_list":["post-63908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tipo-podcast-culture-talks","format-podcast"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?<\/title>\n<meta name=\"description\" content=\"O que as pessoas comem na Alemanha? Quais s\u00e3o as comidas t\u00edpicas do pa\u00eds? Ou\u00e7a agora e descubra!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?\" \/>\n<meta property=\"og:description\" content=\"O que as pessoas comem na Alemanha? Quais s\u00e3o as comidas t\u00edpicas do pa\u00eds? Ou\u00e7a agora e descubra!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/\" \/>\n<meta property=\"og:site_name\" content=\"Fluency.io Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-15T17:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-14T21:29:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marcelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/\"},\"author\":{\"name\":\"marcelo\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"headline\":\"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?\",\"datePublished\":\"2022-04-15T17:29:00+00:00\",\"dateModified\":\"2025-02-14T21:29:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/\"},\"wordCount\":465,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/\",\"name\":\"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg\",\"datePublished\":\"2022-04-15T17:29:00+00:00\",\"dateModified\":\"2025-02-14T21:29:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"description\":\"O que as pessoas comem na Alemanha? Quais s\u00e3o as comidas t\u00edpicas do pa\u00eds? Ou\u00e7a agora e descubra!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg\",\"contentUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg\",\"width\":1920,\"height\":1079,\"caption\":\"fluency-academy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluency.io\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/\",\"name\":\"Fluency Academy\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluency.io\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\",\"name\":\"marcelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"caption\":\"marcelo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?","description":"O que as pessoas comem na Alemanha? Quais s\u00e3o as comidas t\u00edpicas do pa\u00eds? Ou\u00e7a agora e descubra!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/","og_locale":"pt_BR","og_type":"article","og_title":"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?","og_description":"O que as pessoas comem na Alemanha? Quais s\u00e3o as comidas t\u00edpicas do pa\u00eds? Ou\u00e7a agora e descubra!","og_url":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/","og_site_name":"Fluency.io Brasil","article_published_time":"2022-04-15T17:29:00+00:00","article_modified_time":"2025-02-14T21:29:18+00:00","og_image":[{"width":1920,"height":1079,"url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marcelo","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/#article","isPartOf":{"@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/"},"author":{"name":"marcelo","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"headline":"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?","datePublished":"2022-04-15T17:29:00+00:00","dateModified":"2025-02-14T21:29:18+00:00","mainEntityOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/"},"wordCount":465,"commentCount":0,"image":{"@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg","articleSection":["Cultura"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/","url":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/","name":"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?","isPartOf":{"@id":"https:\/\/fluency.io\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/#primaryimage"},"image":{"@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg","datePublished":"2022-04-15T17:29:00+00:00","dateModified":"2025-02-14T21:29:18+00:00","author":{"@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"description":"O que as pessoas comem na Alemanha? Quais s\u00e3o as comidas t\u00edpicas do pa\u00eds? Ou\u00e7a agora e descubra!","breadcrumb":{"@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/#primaryimage","url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg","contentUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/625891345a417e00b706a2c6_ALE_Culture-Talks_08_THUMB_PORTAL.jpg","width":1920,"height":1079,"caption":"fluency-academy"},{"@type":"BreadcrumbList","@id":"https:\/\/fluency.io\/br\/blog\/culture-talks-alemao-08-como-sao-as-comidas-tipicas-na-alemanha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluency.io\/br\/"},{"@type":"ListItem","position":2,"name":"Culture Talks Alem\u00e3o: Como s\u00e3o as comidas t\u00edpicas na Alemanha?"}]},{"@type":"WebSite","@id":"https:\/\/fluency.io\/br\/#website","url":"https:\/\/fluency.io\/br\/","name":"Fluency Academy","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluency.io\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f","name":"marcelo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","caption":"marcelo"}}]}},"_links":{"self":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/63908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/comments?post=63908"}],"version-history":[{"count":3,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/63908\/revisions"}],"predecessor-version":[{"id":94226,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/63908\/revisions\/94226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media\/63909"}],"wp:attachment":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media?parent=63908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/categories?post=63908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/tags?post=63908"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/format?post=63908"},{"taxonomy":"trilha","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/trilha?post=63908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}