{"id":64428,"date":"2022-06-09T17:30:00","date_gmt":"2022-06-09T17:30:00","guid":{"rendered":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/"},"modified":"2025-02-28T15:42:42","modified_gmt":"2025-02-28T18:42:42","slug":"fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo","status":"publish","type":"post","link":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/","title":{"rendered":"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo."},"content":{"rendered":"<p><em>\u00a1Hola, mi gente! \ud83d\ude03<\/em>\u200d<\/p>\n<p>Sejam bem-vindos e bem-vindas a mais um epis\u00f3dio da nossa s\u00e9rie de podcasts, o <strong>Fluency News<\/strong>! Aqui voc\u00ea vai treinar a sua escuta e ficar por dentro do que est\u00e1 acontecendo no mundo, sempre com as principais not\u00edcias da semana, tudo em espanhol! Ao longo do epis\u00f3dio, n\u00f3s tamb\u00e9m adicionamos explica\u00e7\u00f5es em portugu\u00eas das coisas que achamos que precisam de mais aten\u00e7\u00e3o, assim voc\u00ea n\u00e3o perde nenhum detalhe!<\/p>\n<p>Neste epis\u00f3dio falamos sobre o quadro da Mona Lisa ter sido atacado com um bolo, sobre novidades de Stranger Things e sobre a descoberta da maior planta do mundo na Austr\u00e1lia.<\/p>\n<h2 data-start=\"296\" data-end=\"330\">Saiba como aproveitar este podcast<\/h2>\n<p><strong data-start=\"333\" data-end=\"347\"><span class=\"x19la9d6 x1fc57z9 x6ikm8r x10wlt62 x19co3pv x1g5zs5t xfibh0p xiy17q3 x1xsqp64 x1lkfr7t xexx8yu x4uap5 x18d9i69 xkhd6sd\"><span class=\"xrtxmta x1bhl96m\">\ud83d\udd39 <\/span><\/span>Iniciantes<\/strong>: Leia a transcri\u00e7\u00e3o antes de ouvir e anote palavras desconhecidas.<\/p>\n<p><strong data-start=\"419\" data-end=\"437\"><span class=\"x19la9d6 x1fc57z9 x6ikm8r x10wlt62 x19co3pv x1g5zs5t xfibh0p xiy17q3 x1xsqp64 x1lkfr7t xexx8yu x4uap5 x18d9i69 xkhd6sd\"><span class=\"xrtxmta x1bhl96m\">\ud83d\udd39 <\/span><\/span>Intermedi\u00e1rios<\/strong>: Ou\u00e7a o podcast acompanhando a transcri\u00e7\u00e3o.<\/p>\n<p><strong data-start=\"486\" data-end=\"499\"><span class=\"x19la9d6 x1fc57z9 x6ikm8r x10wlt62 x19co3pv x1g5zs5t xfibh0p xiy17q3 x1xsqp64 x1lkfr7t xexx8yu x4uap5 x18d9i69 xkhd6sd\"><span class=\"xrtxmta x1bhl96m\">\ud83d\udd39 <\/span><\/span>Avan\u00e7ados<\/strong>: Ou\u00e7a sem a transcri\u00e7\u00e3o e tente compreender o m\u00e1ximo poss\u00edvel.<\/p>\n<p>Toda semana temos um novo epis\u00f3dio do <strong>Fluency News<\/strong>, n\u00e3o deixe de escutar!<\/p>\n<p>\u200d<em>\u00a1Hasta pronto!<\/em><\/p>\n<h2>Transcri\u00e7\u00e3o do epis\u00f3dio<\/h2>\n<p><em>\u00a1Hola, mi gente! \u00a1Es un gustazo tenerte de nuevo aqu\u00ed, en Fluency New el podcast de not\u00edcias de Fluency Academy. Soy Cass tu profe mexicana, y estoy muy contenta en acompa\u00f1arte hoy en tu pr\u00e1ctica de espa\u00f1ol, mientras sigues siendo un ciudadano del mundo bien informado.\u00a0\u00a0<\/em><\/p>\n<p><em>O contato frequente com o idioma que voc\u00ea est\u00e1 aprendendo \u00e9 mega importante pra garantir o seu sucesso. Voc\u00ea pode fazer isso de maneiras diferentes, e uma delas \u00e9 fazendo um curso de espanhol! Voc\u00ea sabia que a Fluency Academy conta com cursos online completos em 8 idiomas. Para se inscrever na nossa lista de espera e desbloquear um novo idioma \u00e9 s\u00f3 clicar no link que est\u00e1 na descri\u00e7\u00e3o desse epis\u00f3dio. \u00c9 bem rapidinho!<\/em><\/p>\n<p><em>En este episodio, vamos a hablar de algunas de las historias m\u00e1s candentes de esta semana, y tendremos algunas explicaciones en portugu\u00e9s para aclarar algo que requiera m\u00e1s atenci\u00f3n.<\/em><\/p>\n<p><em>\u00bfListo, lista? \u00a1A empezar!<\/em><\/p>\n<p><em>Empezamos este episodio hablando de ella, por supuesto. Uno de los cuadros m\u00e1s famosos del mundo, &#8220;La Gioconda&#8221;, m\u00e1s conocida como la &#8220;Mona Lisa&#8221;, fue atacado en el Museo del Louvre la semana pasada.<\/em><\/p>\n<p><em>\u00bfPor d\u00f3nde empezar? Un hombre con peluca atraves\u00f3 el control de seguridad en una silla de ruedas e intent\u00f3 romper el cristal protector que recubre el cuadro. Al ser a prueba de balas, digamos que el tipo no tuvo \u00e9xito. Descontento con su intento fallido, el hombre decidi\u00f3 lanzarle lo que parece ser un pastel, S\u00cd, UN PASTEL. El hombre lanz\u00f3 un pastel a la Mona Lisa.\u00a0<\/em><\/p>\n<p><em>&#8220;Piensa en la Tierra&#8221;, grit\u00f3 el atacante. &#8220;Hay gente que est\u00e1 destruyendo la Tierra. Piensa en ello. Los artistas te dicen: piensa en la Tierra. Por eso he hecho esto&#8221;, justific\u00f3.<\/em><\/p>\n<p><em>La seguridad le escolt\u00f3 fuera del museo, donde se exhibe desde 1797, y afortunadamente la obra maestra de Leonardo da Vinci del siglo XVI no sufri\u00f3 da\u00f1os gracias al cristal antibalas que se instal\u00f3 tras los ataques anteriores.\u00a0<\/em><\/p>\n<p><em>No es de extra\u00f1ar que necesite ese tipo de protecci\u00f3n. El cuadro de 77 cent\u00edmetros ha pasado por muchas cosas a lo largo de los siglos. Adem\u00e1s de ser robada y da\u00f1ada, le lanzaron pintura y tazas. Incluso estuvo en los ba\u00f1os de los reyes antes de ser colocada en el museo. Pobre Mona Lisa. Esperemos que tenga algo de paz y tranquilidad durante un tiempo.<\/em><\/p>\n<p><em>Vem c\u00e1, voc\u00ea faz parte daquele grupo de aprendizes que at\u00e9 hoje n\u00e3o entende essas palavras e fica confuso: Pastel, torta ou bolo, afinal qual \u00e9 o certo? Depende do pa\u00eds, mas fica ligado, ligada porque pastel \u00e9 um falso cognato entre portugu\u00eas e espanhol. No geral, pastel \u00e9 um bolo ou torta doce. No M\u00e9xico pastel significa \u201cbolo de anivers\u00e1rio\u201d, por exemplo. E para dizer pastel, aquele com carne mo\u00edda? A\u00ed o mais similar que temos s\u00e3o as empanadas. Mas, \u00e9 importante voc\u00ea ter cuidado e entender que nessa not\u00edcia estamos falando de um <\/em><strong><em>bolo<\/em><\/strong><em> que foi jogado no famoso quadro, Mona Lisa, e n\u00e3o um <\/em><strong><em>pastel <\/em><\/strong><em>como fritos recheados de carne mo\u00edda. Humm me deu at\u00e9 fome depois disso hahaha.<\/em><\/p>\n<p><em>Esse tipo de linguagem \u00e9 bem importante voc\u00ea saber, para n\u00e3o ser pego pelos falsos amigos ou cognatos. Uma outra forma de aprender vocabul\u00e1rio como essse, express\u00f5es e outras frases \u00e9 escutando nossos outros podcasts! Cada podcast nosso explora um t\u00f3pico diferente. Quer praticar a sua pron\u00fancia? Voc\u00ea pode seguir as nossas playlists de Walk \u2018n\u2019 Talk Essentials e Level Up, ou escutar o Pronunciation Bootcamp. Se quiser conhecer a cultura de outros pa\u00edses, voc\u00ea pode escutar o Culture Talks. Tem tamb\u00e9m o Infinite Vocab, o Go Getter e o Like a Native, que \u00e9 perfeito pra voc\u00ea entender e se comunicar com um nativo. Tudo de gra\u00e7a, pra voc\u00ea expandir o seu conhecimento!<\/em><\/p>\n<p><em>Agora vamos falar do assunto do momento: Stranger Things. Envia esse epis\u00f3dio para aquele seu amigo fascinado pela s\u00e9rie pra ele ficar sabendo de todas essas novidades!<\/em><\/p>\n<p><em>La semana pasada hablamos de la temporada 4 volumen 1 que se estren\u00f3 el viernes 27, y ahora aqu\u00ed vengo con lo que pas\u00f3 durante la semana. El volumen 1 de &#8216;Stranger Things 4&#8217; registr\u00f3 el mayor fin de semana de estreno de la historia para una serie original de Netflix con 286.79 millones de horas vistas, superando a la segunda temporada de Bridgerton, que obtuvo 193 millones.\u00a0<\/em><\/p>\n<p><em>El primer volumen solo tiene siete episodios, pero todos ellos duran m\u00e1s de una hora, por lo que puede que te lleve un poco m\u00e1s de tiempo <\/em><strong><em>darte un atrac\u00f3n<\/em><\/strong><em>.\u00a0<\/em><\/p>\n<p><em>Los fans esperan ahora con impaciencia el segundo volumen, que se estrenar\u00e1 el 1 de julio y tendr\u00e1 solo dos episodios. Pero no te preocupes, porque ser\u00e1n de m\u00e1s de una hora y el \u00faltimo durar\u00e1 m\u00e1s de dos horas y media. Eso es b\u00e1sicamente una pel\u00edcula de Marvel, as\u00ed que supongo que Netflix tendr\u00e1 tiempo suficiente para responder a las preguntas que surgieron en el final del volumen 1.\u00a0<\/em><\/p>\n<p><em>\u00bfYa est\u00e1s emocionado, emocionada? Ah, y si esperas hasta el final del \u00faltimo episodio, encontrar\u00e1s un teaser oculto de lo que puedes esperar del pr\u00f3ximo volumen. Seguro que si no te has dado cuenta, volver\u00e1s para ver lo que te has perdido.<\/em><\/p>\n<p><em>Voc\u00ea conhece a express\u00e3o darte un atrac\u00f3n? Ela \u00e9 muito usada no sentido de comida, comer demais compulsivamente, mas n\u00e3o \u00e9 s\u00f3 isso. Atrac\u00f3n tamb\u00e9m pode ser usado em outros contextos para falar de qualquer coisa que voc\u00ea faz excessivamente. No quesito s\u00e9ries, \u00e9 como \u201cmaratonar uma s\u00e9rie\u201d \u201cver tudo numa tacada s\u00f3\u201d, em um s\u00f3 dia. Ou seja, a not\u00edcia fala que pelo fato dos novos epis\u00f3dios serem bem longos, levar\u00e1 um pouco mais de tempo para ver tudo de uma vez s\u00f3.<\/em><\/p>\n<p><em>Y por \u00faltimo, pero no por ello menos importante, vamos a intentar imaginar lo que crees que es una planta grande. Seguro que te sorprender\u00e1 saber que no es ni de lejos lo que imaginabas. La planta m\u00e1s grande del mundo fue encontrada en lo que hoy se conoce como Shark Bay, frente a la costa occidental australiana.\u00a0<\/em><\/p>\n<p><em>Una sola hierba marina de 4.500 a\u00f1os de antig\u00fcedad se extend\u00eda por 200 kil\u00f3metros cuadrados de fondo marino. \u00bfY cu\u00e1nto es eso? &#8220;Solo&#8221; unos 28.000 campos de f\u00fatbol.\u00a0<\/em><\/p>\n<p><em>Los cient\u00edficos de la Universidad de Australia Occidental y la Universidad de Flinders pensaron inicialmente que la planta era una <\/em><strong><em>pradera <\/em><\/strong><em>de diferentes pastos marinos, pero las pruebas gen\u00e9ticas demostraron lo contrario.<\/em><\/p>\n<p><em>La especie se encuentra habitualmente en las costas del sur de Australia y los cient\u00edficos pensaron en un primer momento que toda ella estaba formada por m\u00e1s de una planta, pero las muestras tomadas en lugares separados por 180 km sugirieron que no hab\u00eda varios ejemplares.<\/em><\/p>\n<p><em>&#8220;Pensamos &#8216;\u00bfqu\u00e9 demonios est\u00e1 pasando aqu\u00ed?'&#8221;, dijo el Dr. Martin Breed, ec\u00f3logo de la Universidad de Flinders. &#8220;Est\u00e1bamos completamente perplejos&#8221;.<\/em><\/p>\n<p><em>La \u00fanica planta se extiende ahora como una <\/em><strong><em>pradera<\/em><\/strong><em>, proporcionando un h\u00e1bitat a una enorme variedad de especies marinas, como tortugas, delfines, cangrejos y peces.<\/em><\/p>\n<p><em>Nessa not\u00edcia, aparecem algumas vezes a palavra pradera. Pradera nada mais \u00e9 que uma extens\u00e3o de campo natural, longas extens\u00f5es de pasto verde, um prado, ou campina no portugu\u00eas.<\/em><\/p>\n<p><em>Y con esa historia terminamos el episodio de hoy. Pero no te preocupes, \u00a1volveremos la semana que viene!\u00a0<\/em><\/p>\n<p><em>E se voc\u00ea sonha em aprender ingl\u00eas, espanhol, franc\u00eas, italiano, alem\u00e3o, japon\u00eas, mandarim ou coreano, se inscreva na nossa lista de espera para come\u00e7ar seus estudos em um novo idioma. O link est\u00e1 na descri\u00e7\u00e3o desse epis\u00f3dio.<\/em><\/p>\n<p><em>Os epis\u00f3dios do Fluency News saem toda ter\u00e7a feira! N\u00e3o esque\u00e7a de voltar na pr\u00f3xima semana, pra continuar praticando suas habilidades de escuta, e se manter informado sobre tudo que acontece ao redor do mundo.<\/em><\/p>\n<p><em>Aqu\u00ed se despide tu profe Cass Arag\u00f3n. \u00a1Besitos y hasta pronto! \u00a1Tchau!\u00a0\u00a0<\/em><\/p>\n<h2>\u200dFuentes.\u200d<\/h2>\n<p><em>\u200d<\/em><strong><em>Mona Lisa es atacada.<\/em><\/strong><a href=\"https:\/\/g1.globo.com\/mundo\/noticia\/2022\/05\/29\/quadro-da-monalisa-e-atacado-por-visitante-no-louvre.ghtml\"><em><br \/>\nhttps:\/\/g1.globo.com\/mundo\/noticia\/2022\/05\/29\/quadro-da-monalisa-e-atacado-por-visitante-no-louvre.ghtml<\/em><\/a><a href=\"https:\/\/www.washingtonpost.com\/world\/2022\/05\/30\/mona-lisa-smear\/\"><em><br \/>\nhttps:\/\/www.washingtonpost.com\/world\/2022\/05\/30\/mona-lisa-smear\/<\/em><\/a><a href=\"https:\/\/nypost.com\/2022\/05\/30\/mona-lisa-attacked-by-cake-throwing-climate-activist\/\"><em><br \/>\nhttps:\/\/nypost.com\/2022\/05\/30\/mona-lisa-attacked-by-cake-throwing-climate-activist\/<\/em><\/a><em>\u200d<\/em><\/p>\n<p><em>\u200d<\/em><strong><em>Stranger Things<\/em><\/strong><em><br \/>\n\u200d<\/em><a href=\"https:\/\/deadline.com\/2022\/05\/stranger-things-4-volume-1-netflix-viewership-records-premiere-weekend-1235035965\/\"><em>https:\/\/deadline.com\/2022\/05\/stranger-things-4-volume-1-netflix-viewership-records-premiere-weekend-1235035965\/<\/em><\/a><em>\u00a0<\/em><a href=\"https:\/\/rollingstone.uol.com.br\/entretenimento\/stranger-things-4-volume-2-dara-soco-no-coracao-do-publico-diz-diretor\/\"><em><br \/>\nhttps:\/\/rollingstone.uol.com.br\/entretenimento\/stranger-things-4-volume-2-dara-soco-no-coracao-do-publico-diz-diretor\/<\/em><\/a><em>\u00a0<\/em><\/p>\n<p><em>\u200d<\/em><strong><em>La planta m\u00e1s grande del mundo: Los cient\u00edficos quedan &#8220;asombrados&#8221; por la hierba marina de 180 km de longitud descubierta frente a Australia<\/em><\/strong><a href=\"https:\/\/www.euronews.com\/green\/2022\/06\/01\/world-s-largest-plant-scientists-blown-away-by-180km-long-seagrass-discovered-off-australi\"><em><br \/>\nhttps:\/\/www.euronews.com\/green\/2022\/06\/01\/world-s-largest-plant-scientists-blown-away-by-180km-long-seagrass-discovered-off-australi<\/em><\/a><a href=\"https:\/\/www.theguardian.com\/environment\/2022\/jun\/01\/what-the-hell-australian-scientists-discover-biggest-plant-on-earth-off-wa-coast\"><em><br \/>\nhttps:\/\/www.theguardian.com\/environment\/2022\/jun\/01\/what-the-hell-australian-scientists-discover-biggest-plant-on-earth-off-wa-coast<\/em><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Curtiu do conte\u00fado? Confira o <a href=\"https:\/\/fluency.io\/br\/cursos\/espanhol\/\">curso de espanhol<\/a>\u00a0completo e veja as ofertas exclusivas para alunos aqui do portal.<\/p>\n<p><em>Hasta la pr\u00f3xima vez!! \ud83d\udc4b<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De un pastel en la Mona Lisa hasta el descubrimiento de la mayor planta del mundo. \u00a1Ponte tus aud\u00edfonos y escucha!<\/p>\n","protected":false},"author":6,"featured_media":64429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":[183],"meta":{"inline_featured_image":false,"footnotes":""},"categories":[163],"tags":[],"trilha":[],"class_list":["post-64428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tipo-podcast-fluency-news","format-podcast"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.<\/title>\n<meta name=\"description\" content=\"A nova temporada de Stranger Things, um bolo lan\u00e7ado na Mona Lisa e muito mais na nova edi\u00e7\u00e3o do seu podcast de not\u00edcias em espanhol! Ou\u00e7a agora mesmo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.\" \/>\n<meta property=\"og:description\" content=\"A nova temporada de Stranger Things, um bolo lan\u00e7ado na Mona Lisa e muito mais na nova edi\u00e7\u00e3o do seu podcast de not\u00edcias em espanhol! Ou\u00e7a agora mesmo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fluency.io Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T17:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-28T18:42:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1421\" \/>\n\t<meta property=\"og:image:height\" content=\"795\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marcelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/\"},\"author\":{\"name\":\"marcelo\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"headline\":\"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.\",\"datePublished\":\"2022-06-09T17:30:00+00:00\",\"dateModified\":\"2025-02-28T18:42:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/\"},\"wordCount\":1655,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/\",\"name\":\"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png\",\"datePublished\":\"2022-06-09T17:30:00+00:00\",\"dateModified\":\"2025-02-28T18:42:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"description\":\"A nova temporada de Stranger Things, um bolo lan\u00e7ado na Mona Lisa e muito mais na nova edi\u00e7\u00e3o do seu podcast de not\u00edcias em espanhol! Ou\u00e7a agora mesmo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png\",\"contentUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png\",\"width\":1421,\"height\":795,\"caption\":\"fluency-academy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluency.io\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/\",\"name\":\"Fluency Academy\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluency.io\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\",\"name\":\"marcelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"caption\":\"marcelo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.","description":"A nova temporada de Stranger Things, um bolo lan\u00e7ado na Mona Lisa e muito mais na nova edi\u00e7\u00e3o do seu podcast de not\u00edcias em espanhol! Ou\u00e7a agora mesmo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/","og_locale":"pt_BR","og_type":"article","og_title":"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.","og_description":"A nova temporada de Stranger Things, um bolo lan\u00e7ado na Mona Lisa e muito mais na nova edi\u00e7\u00e3o do seu podcast de not\u00edcias em espanhol! Ou\u00e7a agora mesmo.","og_url":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/","og_site_name":"Fluency.io Brasil","article_published_time":"2022-06-09T17:30:00+00:00","article_modified_time":"2025-02-28T18:42:42+00:00","og_image":[{"width":1421,"height":795,"url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marcelo","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/#article","isPartOf":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/"},"author":{"name":"marcelo","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"headline":"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.","datePublished":"2022-06-09T17:30:00+00:00","dateModified":"2025-02-28T18:42:42+00:00","mainEntityOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/"},"wordCount":1655,"commentCount":0,"image":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png","articleSection":["Cultura"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/","url":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/","name":"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo.","isPartOf":{"@id":"https:\/\/fluency.io\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/#primaryimage"},"image":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png","datePublished":"2022-06-09T17:30:00+00:00","dateModified":"2025-02-28T18:42:42+00:00","author":{"@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"description":"A nova temporada de Stranger Things, um bolo lan\u00e7ado na Mona Lisa e muito mais na nova edi\u00e7\u00e3o do seu podcast de not\u00edcias em espanhol! Ou\u00e7a agora mesmo.","breadcrumb":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/#primaryimage","url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png","contentUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/629fa9113aa1239146fffda9_Captura-de-tela-2022-06-07-163555.png","width":1421,"height":795,"caption":"fluency-academy"},{"@type":"BreadcrumbList","@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-espanhol-72-un-pastel-en-la-mona-lisa-stranger-things-4-y-el-descubrimiento-de-la-planta-mas-grande-del-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluency.io\/br\/"},{"@type":"ListItem","position":2,"name":"Fluency News Espanhol: Un pastel en la Mona Lisa, Stranger Things 4 y el descubrimiento de la planta m\u00e1s grande del mundo."}]},{"@type":"WebSite","@id":"https:\/\/fluency.io\/br\/#website","url":"https:\/\/fluency.io\/br\/","name":"Fluency Academy","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluency.io\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f","name":"marcelo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","caption":"marcelo"}}]}},"_links":{"self":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/64428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/comments?post=64428"}],"version-history":[{"count":2,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/64428\/revisions"}],"predecessor-version":[{"id":96227,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/64428\/revisions\/96227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media\/64429"}],"wp:attachment":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media?parent=64428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/categories?post=64428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/tags?post=64428"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/format?post=64428"},{"taxonomy":"trilha","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/trilha?post=64428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}