{"id":66292,"date":"2022-09-23T17:30:00","date_gmt":"2022-09-23T17:30:00","guid":{"rendered":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/"},"modified":"2024-08-26T11:34:28","modified_gmt":"2024-08-26T14:34:28","slug":"fluency-news-frances-87","status":"publish","type":"post","link":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/","title":{"rendered":"Fluency News Franc\u00eas #87 &#8211; L&#8217;alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l&#8217;Ukraine"},"content":{"rendered":"<p><em>Salut, tout le monde !<\/em>\u200d<\/p>\n<p>Sejam bem-vindos e bem-vindas a mais um epis\u00f3dio da nossa s\u00e9rie de podcasts, o <strong>Fluency News<\/strong>! Aqui voc\u00ea vai treinar a sua escuta e ficar por dentro do que est\u00e1 acontecendo no mundo, sempre com as principais not\u00edcias da semana, tudo em franc\u00eas! Ao longo do epis\u00f3dio, n\u00f3s tamb\u00e9m adicionamos explica\u00e7\u00f5es em portugu\u00eas dos pontos que achamos que precisam de mais aten\u00e7\u00e3o, assim voc\u00ea n\u00e3o perde nenhum detalhe!<\/p>\n<p>Neste epis\u00f3dio, voc\u00ea vai saber mais sobre os pa\u00edses que est\u00e3o repensando suas alian\u00e7as depois da morte da rainha Elizabeth, as tropas russas que est\u00e3o finalmente deixando algumas regi\u00f5es da Ucr\u00e2nia e a fortuna que o Rock in Rio gerou para o Rio de Janeiro. <em>On y va ?<\/em>\u200d<\/p>\n<p>N\u00e3o deixe de conferir nossa p\u00e1gina do Instagram, @fluencytvfrances!<br \/>\nToda semana, temos um novo epis\u00f3dio do <strong>Fluency News<\/strong>, n\u00e3o deixe de escutar!<em><\/em>\u200d<\/p>\n<p>\u200d<em>Bisous et \u00e0 la prochaine !<\/em><\/p>\n<h4>Transcri\u00e7\u00e3o do epis\u00f3dio<\/h4>\n<p>Salut tout le monde ! Bienvenue dans ce nouvel \u00e9pisode de Fluency News. Je suis Teurra ta prof de fran\u00e7ais chez Fluency Academy, et je suis ravie de savoir que tu es l\u00e0. Ensemble, nous verrons certaines des nouvelles les plus pertinentes de cette semaine et, si n\u00e9cessaire, nous aurons des explications en portugais.<\/p>\n<p>Antes de descobrirmos o que t\u00e1 rolando pelo mundo, deixa s\u00f3 eu te lembrar: se voc\u00ea sonha em estudar franc\u00eas, espanhol, ingl\u00eas, italiano, alem\u00e3o, japon\u00eas, mandarim ou coreano, se inscreva na nossa lista de espera para estudar com a gente e tirar esse sonho do papel. \u00c9 bem rapidinho, leva s\u00f3 15 segundinhos para voc\u00ea dar o primeiro passo! O link t\u00e1 na descri\u00e7\u00e3o, corre l\u00e1!<\/p>\n<p>Alors ! On commence ?<\/p>\n<p>O longo reinado da rainha Elizabeth chegou ao fim depois de 70 anos, mas, e agora? Ser\u00e1 que algo vai mudar nas rela\u00e7\u00f5es dos outros pa\u00edses com a coroa? De acordo com a nossa primeira not\u00edcia, parece que sim! Bora entender o que t\u00e1 acontecendo, se liga aqui:<\/p>\n<p>Bien que la couronne britannique soit g\u00e9n\u00e9ralement associ\u00e9e \u00e0 la Grande-Bretagne et au Royaume-Uni, elle veut rassembler plusieurs pays, la plupart des pays qui ont \u00e9t\u00e9 colonis\u00e9s par la monarchie britannique. Ce rassemblement est appel\u00e9 en anglais le Commonwealth.<\/p>\n<p>Le Commonweath tente de travailler pour promouvoir des id\u00e9es similaires en mati\u00e8re de d\u00e9mocratie et de soci\u00e9t\u00e9, et la reine \u00c9lisabeth \u00e9tait un grand partisan de cette perspective, elle visitait toujours ces pays lorsqu&#8217;elle \u00e9tait sur le tr\u00f4ne. En fait, elle a fait passer le Commonwealth de 6 \u00e0 56 pays et a \u00e9t\u00e9 nomm\u00e9e chef d&#8217;\u00c9tat dans 32 d&#8217;entre eux, mais ce nombre a rapidement diminu\u00e9, puisqu&#8217;il n&#8217;est pas plus que de 14, dont le Canada, l&#8217;Australie et la Nouvelle-Z\u00e9lande.<\/p>\n<p>Les pays ont toujours \u00e9t\u00e9 libres de rester, de rejoindre ou de quitter le Commonwealth, et il semble qu&#8217;avec le d\u00e9c\u00e8s de la Reine, beaucoup d&#8217;entre eux remettent en question l&#8217;alliance et certains ne sont pas totalement d\u2019accord, en particulier les 14 pays qui la consid\u00e8rent toujours comme souveraine.<\/p>\n<p>Les anciennes colonies <strong>ont pris leurs distances <\/strong>de la couronne au cours des 50 derni\u00e8res ann\u00e9es et, l&#8217;ann\u00e9e derni\u00e8re, la Barbade est devenue une r\u00e9publique, ne consid\u00e9rant plus Elizabeth comme leur chef d&#8217;\u00c9tat. Des protestations ont eu lieu dans les pays des Cara\u00efbes, notamment une manifestation contre la pr\u00e9sence de la monarchie lors de la derni\u00e8re visite du prince William. Par cons\u00e9quent, le couronnement de Charles sera probablement l&#8217;\u00e9l\u00e9ment d\u00e9clencheur de la rupture des liens avec d&#8217;autres pays.<\/p>\n<p>Un professeur des relations internationales \u00e0 l&#8217;Universit\u00e9 de Londres, explique : &#8220;Le Commonwealth doit faire face \u00e0 une tension importante : D&#8217;une part, les personnes trouvent ses espaces utiles \u00e0 la discussion ; d&#8217;autre part, tous ses membres sont conscients qu&#8217;il repr\u00e9sente un pass\u00e9 auquel personne ne veut revenir, une structure imp\u00e9riale. [&#8230;] Les personnes ont de plus en plus envie de s&#8217;\u00e9loigner de cette histoire et de forger leur propre avenir. [&#8230;] Il n&#8217;est pas du tout \u00e9vident pour moi que le prochain chef du Commonwealth soit un membre de la famille royale britannique&#8221;.<\/p>\n<p>Nos resta ent\u00e3o esperar pra ver quais ser\u00e3o as cenas dos pr\u00f3ximos cap\u00edtulos<\/p>\n<p>Nessa primeira not\u00edcia, vou chamar aten\u00e7\u00e3o para um termo que apareceu quase no finalzinho. Repare nessa frase: Les anciennes colonies <strong>ont pris leurs distances <\/strong>de la couronne au cours des 50 derni\u00e8res ann\u00e9es. O que voc\u00ea acha que significa o trecho \u201c<strong>ont pris leurs distances\u201d<\/strong>?<\/p>\n<p>Literalmente, podemos traduzir por \u201cpegou suas distancias\u201d, mas, claro, n\u00e3o falamos dessa forma em portugu\u00eas. Aqui, eu quis dizer que as antigas col\u00f4nias se distanciaram da monarquia nos \u00faltimos 50 anos.<\/p>\n<p>Ent\u00e3o, em franc\u00eas, para dizer se distanciar de algo ou de algu\u00e9m, usamos o verbo \u201cprendre\u201d. Prendre distance. Mas tamb\u00e9m podemos usar o verbo \u201cS\u2019\u00e9loigner\u201d. Por exemplo, a frase \u201cVoc\u00ea se distanciou de mim\u201d pode ser dita das seguintes formas:<\/p>\n<p>Tu t&#8217;es \u00e9loign\u00e9 de moi.<br \/>\nTu as pris de la distance avec moi.<\/p>\n<p>Tudo certinho at\u00e9 aqui?<\/p>\n<p>Voc\u00ea acredita que a guerra entre a Russia e a Ucr\u00e2nia j\u00e1 est\u00e1 completando 7 meses? Essa sequ\u00eancia de dias horr\u00edveis talvez tenha encontrado um momento de esperan\u00e7a para algumas das cidades ucranianas que foram invadidas, e antes de come\u00e7ar, j\u00e1 vou avisar que por for\u00e7a do h\u00e1bito franc\u00eas eu tamb\u00e9m vou afrancesar os nomes das cidades!<\/p>\n<p>Les villes de l&#8217;est de l&#8217;Ukraine pourraient enfin \u00eatre en mesure de respirer et de dormir en paix ! Apr\u00e8s de nombreuses planifications strat\u00e9giques, les troupes ukrainiennes ont pu repousser et coincer les groupes russes, les faisant partir pour \u00e9chapper \u00e0 leur encerclement.<\/p>\n<p>Les troupes russes ont quitt\u00e9 la r\u00e9gion de Kharkiv <strong>\u00e0 la h\u00e2te<\/strong> et ont fini par laisser derri\u00e8re elles un nombre important d&#8217;armes et de munitions dans une retraite pr\u00e9cipit\u00e9e, alors que la guerre atteignait 200 jours, le dimanche 11 septembre. Peu apr\u00e8s la retraite, un de leurs d\u00e9p\u00f4ts de munitions a \u00e9t\u00e9 dynamit\u00e9 par les forces ukrainiennes.<\/p>\n<p>Le chef militaire ukrainien a d\u00e9clar\u00e9 que les actions de l&#8217;Ukraine avaient lib\u00e9r\u00e9 environ 3.000 kilom\u00e8tres carr\u00e9s au cours des derni\u00e8res semaines, laissant seulement 50 kilom\u00e8tres \u00e0 lib\u00e9rer de ce c\u00f4t\u00e9. Le minist\u00e8re russe de la d\u00e9fense d\u00e9ment cette affirmation et affirme que le retrait s&#8217;est produit parce que des hommes suppl\u00e9mentaires \u00e9taient n\u00e9cessaires dans la r\u00e9gion de Donetsk, un territoire diff\u00e9rent.<\/p>\n<p>Mais de nombreux signes indiquent que la d\u00e9fense russe commence \u00e0 perdre du terrain, que les troupes pourraient manquer de munitions et que des cessez-le-feu ou des redditions locales sont organis\u00e9s, notamment dans la r\u00e9gion de Kharkiv.<\/p>\n<p>Par peur de repr\u00e9sailles, m\u00eame les citoyens ukrainiens qui ont coop\u00e9r\u00e9 avec les troupes russes plient bagage et quittent la r\u00e9gion, essayant d&#8217;entrer en Russie pour \u00e9chapper au conflit et \u00e0 leurs accusations de trahison. Les autorit\u00e9s de la province de Kharkiv ont d\u00e9clar\u00e9 que 50 dossiers avaient \u00e9t\u00e9 ouverts pour ces accusations, concernant notamment des maires, des juges et des officiers de police.<\/p>\n<p>E a\u00ed? Bom, vamos l\u00e1 pra nossa dica da vez! Aqui no in\u00edcio da not\u00edcia, voc\u00ea ouviu que: Les troupes russes ont quitt\u00e9 la r\u00e9gion de Kharkiv <strong>\u00e0 la h\u00e2te<\/strong>. \u00c0 la h\u00e2te, o que isso quer dizer?<\/p>\n<p>Bom, vamos por partes. A palavra \u201ch\u00e2te\u201d \u00e9 bem comum no dia a dia dos falantes de franc\u00eas quando usada na express\u00e3o \u201cavoir h\u00e2te de\u201d. Ela \u00e9 usada para dizer que estamos ansiosos para alguma coisa, por exemplo: J&#8217;ai h\u00e2te de voir ce film. (Estou ansiosa para ver esse filme) ou J&#8217;ai h\u00e2te de retrouver mon copain. (Estou ansiosa para reencontrar meu namorado.).<\/p>\n<p>Aqui na not\u00edcia, a palavra foi usada de forma um pouco diferente, sem a part\u00edcula \u201cavoir de\u201d, mas traz um sentido parecido \u00e0 frase da nossa not\u00edcia. Quando falamos sobre fazer algo \u201c\u00e0 la h\u00e2te\u201d, queremos dizer que estamos fazendo algo \u201c\u00e0s pressas\u201d, quase que de forma precipitada, sem pensar. Vamos dar uma olhada agora na tradu\u00e7\u00e3o da frase da nossa not\u00edcia:<\/p>\n<p>Les troupes russes ont quitt\u00e9 la r\u00e9gion de Kharkiv <strong>\u00e0 la h\u00e2te<\/strong>.<br \/>\nAs tropas russas deixaram a regi\u00e3o de Kharkiv \u00e0s pressas.<\/p>\n<p>E vamos falar de coisa boa na nossa \u00faltima not\u00edcia de hoje? Vamos falar de m\u00fasica? Que o Rock in Rio \u00e9 um dos maiores e mais ic\u00f4nicos festivais de m\u00fasica do mundo, voc\u00ea j\u00e1 sabe n\u00e9, mas voc\u00ea tem ideia do tanto de dinheiro que o festival movimenta? Vem comigo descobrir e aproveita pra mandar o epis\u00f3dio pra galera que comentou sobre o Rock in Rio com voc\u00ea!<\/p>\n<p>Apr\u00e8s trois ans, Rock in Rio est finalement revenu pour l&#8217;\u00e9dition 2022. Pendant deux week-ends, du 2 au 11 septembre, le festival a attir\u00e9 420 000 personnes de l&#8217;ext\u00e9rieur de Rio, plus de 10 000 visiteurs internationaux de 31 pays, soit un total de 700 000 fans.<\/p>\n<p>Parmi les attractions figuraient de grands noms comme Iron Maiden, Justin Bieber, Guns N&#8217; Roses, Green Day, Avril Lavigne, Coldplay et Dua Lipa. Et m\u00eame avec la pluie battante du deuxi\u00e8me week-end, ils ont rendu le public fou, non seulement ceux qui \u00e9taient sur place mais aussi ceux qui regardaient \u00e0 la maison.<\/p>\n<p>Les performances sont devenues des<strong> sujets tendances<\/strong> sur Twitter \u00e0 plusieurs reprises et ont \u00e9t\u00e9 un v\u00e9ritable ph\u00e9nom\u00e8ne national, notamment la performance de Coldplay, ses effets visuels et sa tentative de parler et de chanter en portugais.<\/p>\n<p>&#8220;Apr\u00e8s trois ans, nous avons pu ressentir \u00e0 nouveau l&#8217;\u00e9motion de voir la Cit\u00e9 du Rock pleine de fans qui envahissent les pelouses avec une joie contagieuse et dans le seul but d&#8217;\u00eatre heureux&#8221;, d\u00e9clare Roberto Medina, fondateur et pr\u00e9sident de Rock in Rio.<\/p>\n<p>D&#8217;ailleurs, Medina a de nombreuses raisons d&#8217;\u00eatre heureux. Le festival a cr\u00e9\u00e9 28 000 emplois et g\u00e9n\u00e9r\u00e9 environ 2 milliards de reais pour la ville de Rio. Consid\u00e9r\u00e9 comme le signe d&#8217;un nouveau d\u00e9part, il a ouvert la possibilit\u00e9 d&#8217;\u00e9tendre le festival \u00e0 d&#8217;autres pays comme les \u00c9tats-Unis et le Chili.<\/p>\n<p>Eu adorei ver o Coldplay cantando em portugu\u00eas! E fiquei surpresa ao descobrir que eles tem 8 shows lotados agendados para outubro no Brasil!! Isso que \u00e9 cair nas gra\u00e7as do povo brasileiro, n\u00e3o \u00e9?! E vamos pra nossa \u00faltima dica do dia, que \u00e9 mais uma dica de vocabul\u00e1rio. Aqui na not\u00edcia tivemos a frase: Les performances sont devenues des<strong> sujets tendances<\/strong> sur Twitter(&#8230;).<\/p>\n<p>O que chamamos de \u201csujets tendances\u201d em franc\u00eas nada mais \u00e9 do que os famosos \u201ctrending topics\u201d do twitter! \u201cSujet\u201d significa \u201cassunto\u201d em franc\u00eas, e \u201ctendances\u201d, \u201ctend\u00eancias\u201d. Voil\u00e0 ! S\u00e3o os \u201cassuntos tend\u00eancias\u201d, que, em portugu\u00eas, chamamos de \u201cassuntos mais comentados do twitter\u201d.<\/p>\n<p>Essa dica aqui foi pros twitteros de pant\u00e3o!<\/p>\n<p>Et c&#8217;est avec cette histoire qu\u2019on termine l&#8217;\u00e9pisode d&#8217;aujourd&#8217;hui, mais n&#8217;oublie pas que nous avons un nouvel \u00e9pisode toutes les semaines pour la mise \u00e0 jour des nouvelles.<\/p>\n<p>Lembre-se de que o contato di\u00e1rio com o franc\u00eas \u00e9 essencial para o seu aprendizado! N\u00e3o deixe de conferir o nosso portal FluencyTv.com para mais podcasts como esse e fique ligado na nossa p\u00e1gina do instagram @FluencyTvFrances para n\u00e3o perder nenhuma dica!<\/p>\n<p>Os epis\u00f3dios do Fluency News saem toda ter\u00e7a feira! N\u00e3o esque\u00e7a de voltar na pr\u00f3xima semana pra continuar praticando suas habilidades de escuta, e se manter informado sobre tudo que acontece ao redor do mundo.<\/p>\n<p>Bisous et \u00e0 la prochaine !<\/p>\n<p><strong>Sources:<\/strong>\u200d<\/p>\n<p>\u200d<strong>Countries cutting ties with British monarchy<\/strong><a href=\"https:\/\/abcnews.go.com\/International\/death-queen-elizabeth-ii-charles-now-king-commonwealth\/story?id=89698750\"><br \/>\nhttps:\/\/abcnews.go.com\/International\/death-queen-elizabeth-ii-charles-now-king-commonwealth\/story?id=89698750<\/a><a href=\"https:\/\/news.sky.com\/story\/can-the-commonwealth-survive-the-queens-death-and-should-it-12696348\"><br \/>\nhttps:\/\/news.sky.com\/story\/can-the-commonwealth-survive-the-queens-death-and-should-it-12696348<\/a><a href=\"https:\/\/www.theguardian.com\/world\/2022\/sep\/12\/monday-briefing-commonwealth-charles-first-edition\"><br \/>\nhttps:\/\/www.theguardian.com\/world\/2022\/sep\/12\/monday-briefing-commonwealth-charles-first-edition<\/a><\/p>\n<p>\u200d<strong>Coldplay Rock in Rio<\/strong><a href=\"https:\/\/www.correiobraziliense.com.br\/diversao-e-arte\/2022\/09\/5036019-coldplay-rouba-a-cena-no-penultimo-dia-do-rock-in-rio.html\"><br \/>\nhttps:\/\/www.correiobraziliense.com.br\/diversao-e-arte\/2022\/09\/5036019-coldplay-rouba-a-cena-no-penultimo-dia-do-rock-in-rio.html<\/a><a href=\"https:\/\/www.nme.com\/features\/opinion\/brazil-rock-in-rio-capped-off-festival-season-in-style-green-day-coldplay-dua-lipa-3308264\"><br \/>\nhttps:\/\/www.nme.com\/features\/opinion\/brazil-rock-in-rio-capped-off-festival-season-in-style-green-day-coldplay-dua-lipa-3308264<\/a><a href=\"https:\/\/www.iq-mag.net\/2022\/09\/rock-in-rio-generates-2bn-reals-in-economic-impact\/\"><br \/>\nhttps:\/\/www.iq-mag.net\/2022\/09\/rock-in-rio-generates-2bn-reals-in-economic-impact\/<\/a><strong><\/strong>\u200d<\/p>\n<p>\u200d<strong>Russians leaving Ukraine<\/strong><a href=\"https:\/\/news.sky.com\/story\/ukraine-may-have-chance-to-throw-russians-out-military-analyst-says-12696364\"><br \/>\nhttps:\/\/news.sky.com\/story\/ukraine-may-have-chance-to-throw-russians-out-military-analyst-says-12696364<\/a><a href=\"https:\/\/www.theguardian.com\/world\/2022\/sep\/13\/collaborators-with-russian-forces-are-fleeing-say-ukrainian-officials\"><br \/>\nhttps:\/\/www.theguardian.com\/world\/2022\/sep\/13\/collaborators-with-russian-forces-are-fleeing-say-ukrainian-officials<\/a><a href=\"https:\/\/abcnews.go.com\/Business\/wireStory\/ukraine-pushes-russia-retreat-counteroffensive-89686831\"><br \/>\nhttps:\/\/abcnews.go.com\/Business\/wireStory\/ukraine-pushes-russia-retreat-counteroffensive-89686831<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sejam bem-vindos e bem-vindas a mais um epis\u00f3dio da nossa s\u00e9rie de podcasts, o Fluency News!<\/p>\n","protected":false},"author":6,"featured_media":66293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":[183],"meta":{"inline_featured_image":false,"footnotes":""},"categories":[163],"tags":[],"trilha":[],"class_list":["post-66292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tipo-podcast-fluency-news","format-podcast"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fluency News Franc\u00eas #87 - L&#039;alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l&#039;Ukraine<\/title>\n<meta name=\"description\" content=\"Neste epis\u00f3dio, voc\u00ea vai saber mais sobre os pa\u00edses que est\u00e3o repensando suas alian\u00e7as depois da morte da rainha Elizabeth, as tropas russas que est\u00e3o finalmente deixando algumas regi\u00f5es da Ucr\u00e2nia e a fortuna que o Rock in Rio gerou para o Rio de Janeiro. Tudo isso no novo epis\u00f3dio do seu podcast de not\u00edcias em franc\u00eas. On y va ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fluency News Franc\u00eas #87 - L&#039;alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l&#039;Ukraine\" \/>\n<meta property=\"og:description\" content=\"Neste epis\u00f3dio, voc\u00ea vai saber mais sobre os pa\u00edses que est\u00e3o repensando suas alian\u00e7as depois da morte da rainha Elizabeth, as tropas russas que est\u00e3o finalmente deixando algumas regi\u00f5es da Ucr\u00e2nia e a fortuna que o Rock in Rio gerou para o Rio de Janeiro. Tudo isso no novo epis\u00f3dio do seu podcast de not\u00edcias em franc\u00eas. On y va ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/\" \/>\n<meta property=\"og:site_name\" content=\"Fluency.io Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T17:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-26T14:34:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1210\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marcelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/\"},\"author\":{\"name\":\"marcelo\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"headline\":\"Fluency News Franc\u00eas #87 &#8211; L&#8217;alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l&#8217;Ukraine\",\"datePublished\":\"2022-09-23T17:30:00+00:00\",\"dateModified\":\"2024-08-26T14:34:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/\"},\"wordCount\":2107,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/\",\"name\":\"Fluency News Franc\u00eas #87 - L'alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l'Ukraine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png\",\"datePublished\":\"2022-09-23T17:30:00+00:00\",\"dateModified\":\"2024-08-26T14:34:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\"},\"description\":\"Neste epis\u00f3dio, voc\u00ea vai saber mais sobre os pa\u00edses que est\u00e3o repensando suas alian\u00e7as depois da morte da rainha Elizabeth, as tropas russas que est\u00e3o finalmente deixando algumas regi\u00f5es da Ucr\u00e2nia e a fortuna que o Rock in Rio gerou para o Rio de Janeiro. Tudo isso no novo epis\u00f3dio do seu podcast de not\u00edcias em franc\u00eas. On y va ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png\",\"contentUrl\":\"https:\\\/\\\/fluency.io\\\/br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/12\\\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png\",\"width\":1210,\"height\":680,\"caption\":\"fluency-academy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/blog\\\/fluency-news-frances-87\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fluency.io\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fluency News Franc\u00eas #87 &#8211; L&#8217;alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l&#8217;Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/fluency.io\\\/br\\\/\",\"name\":\"Fluency Academy\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluency.io\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fluency.io\\\/br\\\/#\\\/schema\\\/person\\\/395d83f1006a72bd4912230eea50ff6f\",\"name\":\"marcelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g\",\"caption\":\"marcelo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fluency News Franc\u00eas #87 - L'alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l'Ukraine","description":"Neste epis\u00f3dio, voc\u00ea vai saber mais sobre os pa\u00edses que est\u00e3o repensando suas alian\u00e7as depois da morte da rainha Elizabeth, as tropas russas que est\u00e3o finalmente deixando algumas regi\u00f5es da Ucr\u00e2nia e a fortuna que o Rock in Rio gerou para o Rio de Janeiro. Tudo isso no novo epis\u00f3dio do seu podcast de not\u00edcias em franc\u00eas. On y va ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/","og_locale":"pt_BR","og_type":"article","og_title":"Fluency News Franc\u00eas #87 - L'alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l'Ukraine","og_description":"Neste epis\u00f3dio, voc\u00ea vai saber mais sobre os pa\u00edses que est\u00e3o repensando suas alian\u00e7as depois da morte da rainha Elizabeth, as tropas russas que est\u00e3o finalmente deixando algumas regi\u00f5es da Ucr\u00e2nia e a fortuna que o Rock in Rio gerou para o Rio de Janeiro. Tudo isso no novo epis\u00f3dio do seu podcast de not\u00edcias em franc\u00eas. On y va ?","og_url":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/","og_site_name":"Fluency.io Brasil","article_published_time":"2022-09-23T17:30:00+00:00","article_modified_time":"2024-08-26T14:34:28+00:00","og_image":[{"width":1210,"height":680,"url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marcelo","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/#article","isPartOf":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/"},"author":{"name":"marcelo","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"headline":"Fluency News Franc\u00eas #87 &#8211; L&#8217;alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l&#8217;Ukraine","datePublished":"2022-09-23T17:30:00+00:00","dateModified":"2024-08-26T14:34:28+00:00","mainEntityOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/"},"wordCount":2107,"commentCount":0,"image":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png","articleSection":["Cultura"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/","url":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/","name":"Fluency News Franc\u00eas #87 - L'alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l'Ukraine","isPartOf":{"@id":"https:\/\/fluency.io\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/#primaryimage"},"image":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/#primaryimage"},"thumbnailUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png","datePublished":"2022-09-23T17:30:00+00:00","dateModified":"2024-08-26T14:34:28+00:00","author":{"@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f"},"description":"Neste epis\u00f3dio, voc\u00ea vai saber mais sobre os pa\u00edses que est\u00e3o repensando suas alian\u00e7as depois da morte da rainha Elizabeth, as tropas russas que est\u00e3o finalmente deixando algumas regi\u00f5es da Ucr\u00e2nia e a fortuna que o Rock in Rio gerou para o Rio de Janeiro. Tudo isso no novo epis\u00f3dio do seu podcast de not\u00edcias em franc\u00eas. On y va ?","breadcrumb":{"@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/#primaryimage","url":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png","contentUrl":"https:\/\/fluency.io\/br\/wp-content\/uploads\/sites\/3\/2023\/12\/632e140fe811c026635fe281_FRA_Fluency-News_87_PORTAL-SPOTIFY-1.png","width":1210,"height":680,"caption":"fluency-academy"},{"@type":"BreadcrumbList","@id":"https:\/\/fluency.io\/br\/blog\/fluency-news-frances-87\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fluency.io\/br\/"},{"@type":"ListItem","position":2,"name":"Fluency News Franc\u00eas #87 &#8211; L&#8217;alliance de la monarchie britannique est remise en question, Rock in Rio pr\u00e9sente des spectacles embl\u00e9matique, et les troupes russes quittent l&#8217;Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/fluency.io\/br\/#website","url":"https:\/\/fluency.io\/br\/","name":"Fluency Academy","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluency.io\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/fluency.io\/br\/#\/schema\/person\/395d83f1006a72bd4912230eea50ff6f","name":"marcelo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9050681441880d21ef4048d38965a107dc5b77bf302f57fa3939973bdafa41d8?s=96&d=mm&r=g","caption":"marcelo"}}]}},"_links":{"self":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/66292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/comments?post=66292"}],"version-history":[{"count":1,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/66292\/revisions"}],"predecessor-version":[{"id":69747,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/posts\/66292\/revisions\/69747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media\/66293"}],"wp:attachment":[{"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/media?parent=66292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/categories?post=66292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/tags?post=66292"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/format?post=66292"},{"taxonomy":"trilha","embeddable":true,"href":"https:\/\/fluency.io\/br\/wp-json\/wp\/v2\/trilha?post=66292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}